{"id":39,"count":4,"description":"","link":"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/","name":"Stays","slug":"stays","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stays - InterContinental Chantilly<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stays - InterContinental Chantilly\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/\" \/>\n<meta property=\"og:site_name\" content=\"InterContinental Chantilly\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chantilly.intercontinental.com\/wp-content\/uploads\/sites\/8\/2024\/12\/intercontinental-chantilly-chateau-mont-royal-logo-ihg-1200x675-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/\",\"url\":\"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/\",\"name\":\"Stays - InterContinental Chantilly\",\"isPartOf\":{\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/chantilly.intercontinental.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/#website\",\"url\":\"https:\/\/chantilly.intercontinental.com\/en\/\",\"name\":\"InterContinental Chantilly Ch\u00e2teau Mont Royal\",\"description\":\"Live the InterContinental Life\",\"publisher\":{\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/#organization\"},\"alternateName\":\"InterContinental Chantilly\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chantilly.intercontinental.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/#organization\",\"name\":\"InterContinental Chantilly Ch\u00e2teau Mont Royal\",\"alternateName\":\"InterContinental Chantilly\",\"url\":\"https:\/\/chantilly.intercontinental.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/chantilly.intercontinental.com\/wp-content\/uploads\/sites\/8\/2024\/11\/intercontinental-chantilly-chateau-mont-royal-logo-ihg.svg\",\"contentUrl\":\"https:\/\/chantilly.intercontinental.com\/wp-content\/uploads\/sites\/8\/2024\/11\/intercontinental-chantilly-chateau-mont-royal-logo-ihg.svg\",\"caption\":\"InterContinental Chantilly Ch\u00e2teau Mont Royal\"},\"image\":{\"@id\":\"https:\/\/chantilly.intercontinental.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stays - InterContinental Chantilly","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/","og_locale":"en_US","og_type":"article","og_title":"Stays - InterContinental Chantilly","og_url":"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/","og_site_name":"InterContinental Chantilly","og_image":[{"width":1200,"height":675,"url":"https:\/\/chantilly.intercontinental.com\/wp-content\/uploads\/sites\/8\/2024\/12\/intercontinental-chantilly-chateau-mont-royal-logo-ihg-1200x675-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/","url":"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/","name":"Stays - InterContinental Chantilly","isPartOf":{"@id":"https:\/\/chantilly.intercontinental.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/chantilly.intercontinental.com\/en\/categorie-produit\/stays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/chantilly.intercontinental.com\/en\/"},{"@type":"ListItem","position":2,"name":"Stays"}]},{"@type":"WebSite","@id":"https:\/\/chantilly.intercontinental.com\/en\/#website","url":"https:\/\/chantilly.intercontinental.com\/en\/","name":"InterContinental Chantilly Ch\u00e2teau Mont Royal","description":"Live the InterContinental Life","publisher":{"@id":"https:\/\/chantilly.intercontinental.com\/en\/#organization"},"alternateName":"InterContinental Chantilly","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chantilly.intercontinental.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/chantilly.intercontinental.com\/en\/#organization","name":"InterContinental Chantilly Ch\u00e2teau Mont Royal","alternateName":"InterContinental Chantilly","url":"https:\/\/chantilly.intercontinental.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chantilly.intercontinental.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/chantilly.intercontinental.com\/wp-content\/uploads\/sites\/8\/2024\/11\/intercontinental-chantilly-chateau-mont-royal-logo-ihg.svg","contentUrl":"https:\/\/chantilly.intercontinental.com\/wp-content\/uploads\/sites\/8\/2024\/11\/intercontinental-chantilly-chateau-mont-royal-logo-ihg.svg","caption":"InterContinental Chantilly Ch\u00e2teau Mont Royal"},"image":{"@id":"https:\/\/chantilly.intercontinental.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/chantilly.intercontinental.com\/en\/wp-json\/wp\/v2\/product_cat\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chantilly.intercontinental.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/chantilly.intercontinental.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/chantilly.intercontinental.com\/en\/wp-json\/wp\/v2\/product?product_cat=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}